{"id":1915,"date":"2026-02-14T07:43:05","date_gmt":"2026-02-14T07:43:05","guid":{"rendered":"https:\/\/www.coeurdalgues.fr\/?post_type=tribe_events&#038;p=1915"},"modified":"2026-02-14T10:06:39","modified_gmt":"2026-02-14T10:06:39","slug":"04-avril","status":"publish","type":"tribe_events","link":"https:\/\/www.coeurdalgues.fr\/index.php\/event\/04-avril\/","title":{"rendered":"04 Avril"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[40],"class_list":["post-1915","tribe_events","type-tribe_events","status-publish","tribe_events_cat-balade-decouverte-des-algues","cat_balade-decouverte-des-algues"],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/1915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/1915\/revisions"}],"predecessor-version":[{"id":1916,"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/tribe_events\/1915\/revisions\/1916"}],"wp:attachment":[{"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1915"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1915"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.coeurdalgues.fr\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=1915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}